{"id":22087,"date":"2021-02-04T07:10:16","date_gmt":"2021-02-04T07:10:16","guid":{"rendered":"https:\/\/demaco-cryogenics.com\/products\/lignes-de-transfert-isolees-sous-vide-vip\/"},"modified":"2026-08-03T15:43:39","modified_gmt":"2026-08-03T13:43:39","slug":"lignes-isolees-sous-vide","status":"publish","type":"products","link":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/","title":{"rendered":"Lignes isol\u00e9es Sous Vide: LSV"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"22087\" class=\"elementor elementor-22087 elementor-3734\" data-elementor-post-type=\"products\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18857c40 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"18857c40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59ff115e\" data-id=\"59ff115e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eb145d elementor-widget elementor-widget-text-editor\" data-id=\"8eb145d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Ligne rigide et flexible isol\u00e9es sous vide<\/strong><\/h2><p><span style=\"font-weight: 400;\">Les lignes isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Ces lignes \u00e0 double paroi permettent une isolation optimale \u00e9vitant le r\u00e9chauffement du liquide cryog\u00e9nique. Les lignes de transfert sont entre autres utilis\u00e9es dans l\u2019industrie maritime que dans les unit\u00e9s de s\u00e9paration d\u2019air.<\/span><\/p><p><span style=\"font-weight: 400;\">La qualit\u00e9 optimale du liquide est obtenue par un vide \u00e9lev\u00e9 combin\u00e9 \u00e0 une isolation multicouches permettant de contrecarrer les effets du rayonnement solaire. Comme indiqu\u00e9 sur la page consacr\u00e9e \u00e0 la technologie du vide, la combinaison d&rsquo;un environnement sous vide et d&rsquo;un \u00e9cran anti-rayonnement garantit que les pertes de chaleur dues \u00e0 la convection, la conduction et au rayonnement soient limit\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Demaco fournit deux types de lignes de transfert:<\/span><\/p><h3><strong>1- Ligne de transfert rigides isol\u00e9s sous vide<\/strong><\/h3><p><span style=\"font-weight: 400;\">La ligne de transfert la plus courante est de type rigide: nous les fournissons sous forme de tron\u00e7ons pr\u00e9-fabriqu\u00e9s. Ces sections de tube ne sont pas flexibles et doivent donc \u00eatre mesur\u00e9es avec pr\u00e9cision avant la fabrication. S&rsquo;ils sont ne serait-ce que quelques millim\u00e8tres trop courts ou trop longs, ils ne pourront \u00eatre install\u00e9s.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71df243 elementor-widget elementor-widget-image\" data-id=\"71df243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"810\" src=\"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/D0405072_VI-piping-optie-2_0_0_In-work-2-1024x810.png\" class=\"attachment-large size-large wp-image-32144\" alt=\"demaco\" srcset=\"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/D0405072_VI-piping-optie-2_0_0_In-work-2-1024x810.png 1024w, https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/D0405072_VI-piping-optie-2_0_0_In-work-2-300x237.png 300w, https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/D0405072_VI-piping-optie-2_0_0_In-work-2-768x607.png 768w, https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/D0405072_VI-piping-optie-2_0_0_In-work-2.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-828d363 elementor-widget elementor-widget-text-editor\" data-id=\"828d363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L&rsquo;image ci-dessus montre comment nos lignes de transfert rigides isol\u00e9es sous vide sont construites.<\/span><\/p><p><span style=\"font-weight: 400;\">Comme on peut le voir, une ligne isol\u00e9e sous vide comprend un tube interne (dit tube process) et un tube externe (\u00e9galement appel\u00e9 jaquette sous vide). Via le port de pompage situ\u00e9e sous le bouchon noir, l&rsquo;inter paroi est tir\u00e9e au vide, tandis que les entretoises vertes sont utilis\u00e9es pour s&rsquo;assurer que les deux tuyaux ne se touchent pas.<\/span><\/p><p><span style=\"font-weight: 400;\">Comme il re\u00e7oit l\u2019azote liquide tr\u00e8s froid, le tube process va r\u00e9tr\u00e9cir tr\u00e8s fortement puis se dilater de nouveau lorsque la ligne se \u201cr\u00e9chauffe\u201d. Afin de parer aux fortes contraintes m\u00e9caniques g\u00e9n\u00e9r\u00e9es par ces dilatations, un compensateur est mont\u00e9 sur le tube process entre 2 entretoises.<\/span><\/p><p><span style=\"font-weight: 400;\">La ligne isol\u00e9e sous vide rigide combine de nombreux avantages dont une performance optimale en terme de perte de charge, de qualit\u00e9 du liquide obtenue, d\u2019esth\u00e9tisme et d\u2019efficience \u00e9conomique par rapport au flexible.<\/span><\/p><h3><b>2. Ligne de transfert flexibles isol\u00e9es sous vide<\/b><\/h3><p><span style=\"font-weight: 400;\">Pour les projets n\u00e9cessitant plus de flexibilit\u00e9, nous proposons \u00e9galement des lignes de transfert flexibles isol\u00e9es sous vide. Ce type de tuyauterie offre une performance d&rsquo;isolation l\u00e9g\u00e8rement inf\u00e9rieure \u00e0 celle des lignes rigides, mais il pr\u00e9sente des avantages significatifs lorsque:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L\u2019installation est temporaire (par exemple, un banc d&rsquo;essai)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Le cheminement de la LSV ne peut \u00eatre mesur\u00e9 pr\u00e9cis\u00e9ment en raison d\u2019un fort encombrement par d\u2019autres \u00e9quipements d\u00e9j\u00e0 en place ou si la connection \u00e0 l\u2019application n\u2019est pas d\u00e9termin\u00e9e au moment de la prise de mesure site.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La ligne est connect\u00e9e \u00e0 une application mobile ou vibrante<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">On doit r\u00e9guli\u00e8rement d\u00e9connecter l\u2019application (par exemple, dans une <\/span><a href=\"https:\/\/demaco-cryogenics.com\/fr\/produits\/systemes-de-remplissage\/\"><span style=\"font-weight: 400;\">station-service<\/span><\/a><span style=\"font-weight: 400;\">)<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75b6c30 elementor-widget elementor-widget-image\" data-id=\"75b6c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"869\" src=\"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/VI-Flex-1.png\" class=\"attachment-large size-large wp-image-32139\" alt=\"\" srcset=\"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/VI-Flex-1.png 1024w, https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/VI-Flex-1-300x255.png 300w, https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/VI-Flex-1-768x652.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12aa988 elementor-widget elementor-widget-text-editor\" data-id=\"12aa988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La ligne flexible est construite de la m\u00eame mani\u00e8re que le type rigide, mais en raison de sa flexibilit\u00e9, il a un diam\u00e8tre l\u00e9g\u00e8rement plus grand par rapport \u00e0 une ligne rigide avec le m\u00eame d\u00e9bit. De plus, la structure de la surface interne est annel\u00e9e, ce qui entra\u00eene une perte de charge l\u00e9g\u00e8rement plus \u00e9lev\u00e9e.<\/span><\/p><p id=\"heading\">Caract\u00e9ristiques<\/p><p><span style=\"font-weight: 400;\">Dans notre usine, nous produisons les tron\u00e7ons de tuyauterie qui sont ensuite assembl\u00e9s sur site. Ces sections peuvent mesurer jusqu&rsquo;\u00e0 12 m\u00e8tres de long et sont disponibles en diff\u00e9rents diam\u00e8tres. Souvent, les flexibles ont un diam\u00e8tre relativement petit de DN15 \/ 25 ou 1 pouce, mais pour une utilisation \u00e0 grande \u00e9chelle, cela peut aller jusqu&rsquo;\u00e0 10 pouces ou plus.<\/span><\/p><p><span style=\"font-weight: 400;\">Nos lignes flexibles sont adapt\u00e9es \u00e0 des pressions de conception standard jusqu&rsquo;\u00e0 PN40 et sont utilis\u00e9es pour des applications telles que: LN2, CO2, LO2, LAr, LNG, LH2 et LHe.<\/span><\/p><p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 nos connaissances et \u00e0 notre technologie, nous pouvons \u00e9galement proposer des pressions plus \u00e9lev\u00e9es, des gaz non standards et des diam\u00e8tres plus importants. Veuillez nous contacter via notre page contact.<\/span><\/p><p><span style=\"font-weight: 400;\">Comme indiqu\u00e9 pr\u00e9c\u00e9demment, la structure de la surface interne de nos lignes de transfert flexibles diff\u00e8re de celle du type rigide. De plus, nos lignes flexibles ont souvent un diam\u00e8tre ext\u00e9rieur l\u00e9g\u00e8rement plus grand.<\/span><\/p><p>\u00a0<\/p><p><b>Pour obtenir davantage d&rsquo;informations techniques, veuillez t\u00e9l\u00e9charger la fiche technique du produit au bas de la page.<\/b><\/p><h2><b>Applications pour les lignes de transfert isol\u00e9es sous vide<\/b><\/h2><p><span style=\"font-weight: 400;\">Une ligne isol\u00e9e sous vide permet de transporter des liquides cryog\u00e9niques avec une qualit\u00e9 optimale gr\u00e2ce \u00e0 de faibles perte de charge et r\u00e9chauffement. Ceci est essentiel dans toutes les industries que nous servons. Par exemple, dans <\/span><i><span style=\"font-weight: 400;\">l&rsquo;industrie alimentaire et l&rsquo;industrie automobile<\/span><\/i><span style=\"font-weight: 400;\">, pour la fourniture d&rsquo;azote liquide et dans <\/span><i><span style=\"font-weight: 400;\">l&rsquo;industrie maritime<\/span><\/i><span style=\"font-weight: 400;\"> pour la fourniture de GNL ou d&rsquo;hydrog\u00e8ne, et dans l&rsquo;industrie de la s\u00e9paration de l&rsquo;air pour le transfert de gaz liquide vers le stockage temporaire et le transport.<\/span><\/p><p><span style=\"font-weight: 400;\">Les lignes sous vides Demaco sont adapt\u00e9es \u00e0 chaque client sur la base de son projet en utilisant des composants standards. En cons\u00e9quence, la gamme d&rsquo;applications de nos LSV est \u00e9norme.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour plus d&rsquo;informations sur les industries que nous servons avec nos produits cryog\u00e9niques, consultez notre <\/span><a href=\"https:\/\/demaco-cryogenics.com\/fr\/industries\/\"><span style=\"font-weight: 400;\">page industries<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p><h2><b>Pas de ligne sous vide sans raccords<\/b><\/h2><p><span style=\"font-weight: 400;\">Parce que nos LSV sont livr\u00e9es en tron\u00e7ons individuels, ils sont raccord\u00e9s ensemble sur site \u00e0 l&rsquo;aide de raccords sp\u00e9ciaux.<\/span><\/p><p><span style=\"font-weight: 400;\">Nous proposons \u00e0 nos clients deux types de raccords diff\u00e9rents:<\/span><\/p><h3><b>1. Raccords Johnston<\/b><\/h3><p><span style=\"font-weight: 400;\">Egalement appel\u00e9\u00a0 raccord ba\u00efonnette, il offre plus de flexibilit\u00e9 que les raccords soud\u00e9s. Le raccord Johnston comprend un m\u00e2le et un femelle, qui peuvent \u00eatre facilement embo\u00eet\u00e9s et solidaris\u00e9s. Aucune soudure n&rsquo;est requise.<\/span><\/p><p><span style=\"font-weight: 400;\">Le raccord Johnston a une perte de chaleur un peu plus importante que le raccord soud\u00e9, mais pr\u00e9sente l&rsquo;avantage de la facilit\u00e9 d&rsquo;installation, de retrait ou de d\u00e9placement. Cela permet m\u00eame au client d&rsquo;installer les lignes de tuyauterie lui-m\u00eame si n\u00e9cessaire.<\/span><\/p><h3><b>2. Raccord soud\u00e9<\/b><\/h3><p><span style=\"font-weight: 400;\">Les raccords soud\u00e9s raccordent de fa\u00e7on permanente 2 tron\u00e7ons de LSV. Un raccord soud\u00e9 assure une s\u00e9curit\u00e9 maximale et offre la meilleure protection contre les d\u00e9perditions de chaleur.\u00a0 Deux types d&rsquo;isolation peuvent \u00eatre choisis pour un raccord soud\u00e9: sous vide ou perlite. L&rsquo;installation d&rsquo;un raccord soud\u00e9 n\u00e9cessite un \u00e9quipement sp\u00e9cialis\u00e9, des connaissances et de l&rsquo;exp\u00e9rience.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ligne rigide et flexible isol\u00e9es sous vide Les lignes isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Ces lignes \u00e0 double paroi permettent une isolation optimale \u00e9vitant le r\u00e9chauffement du liquide cryog\u00e9nique. Les lignes de transfert sont entre autres utilis\u00e9es dans l\u2019industrie maritime que dans les unit\u00e9s de s\u00e9paration d\u2019air. La [&hellip;]<\/p>\n","protected":false},"featured_media":35122,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"tags":[],"industry":[65,137,102,58,180,74,139,140,70,57,138],"class_list":["post-22087","products","type-products","status-publish","has-post-thumbnail","hentry","industry-aerospatial","industry-agro-alimentaire","industry-electronique","industry-gnl","industry-hydrogene-fr","industry-industrie-automobile","industry-industrie-medicale","industry-industrie-pharmaceutique","industry-recherche","industry-separation-de-lair","industry-transport-maritime"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lignes isol\u00e9es Sous Vide: LSV<\/title>\n<meta name=\"description\" content=\"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lignes isol\u00e9es Sous Vide: LSV\" \/>\n<meta property=\"og:description\" content=\"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/\" \/>\n<meta property=\"og:site_name\" content=\"Demaco Cryogenics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/demaconl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T13:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/Vacuum-Insulated-Piping-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DemacoNL\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/\",\"url\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/\",\"name\":\"Lignes isol\u00e9es Sous Vide: LSV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demaco-cryogenics.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Vacuum-Insulated-Piping-2.png\",\"datePublished\":\"2021-02-04T07:10:16+00:00\",\"dateModified\":\"2026-08-03T13:43:39+00:00\",\"description\":\"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/demaco-cryogenics.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Vacuum-Insulated-Piping-2.png\",\"contentUrl\":\"https:\\\/\\\/demaco-cryogenics.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Vacuum-Insulated-Piping-2.png\",\"width\":1152,\"height\":910,\"caption\":\"Vacuum Insulated Piping\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/lignes-isolees-sous-vide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lignes isol\u00e9es Sous Vide: LSV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/\",\"name\":\"Demaco Cryogenics\",\"description\":\"It&#039;s all about cryogenics\",\"publisher\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#organization\",\"name\":\"Demaco Holland B.V.\",\"url\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/demaco-cryogenics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logoDemaco.png\",\"contentUrl\":\"https:\\\/\\\/demaco-cryogenics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logoDemaco.png\",\"width\":195,\"height\":32,\"caption\":\"Demaco Holland B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/demaco-cryogenics.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/demaconl\",\"https:\\\/\\\/x.com\\\/DemacoNL\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/demaco-holland-bv\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC78jyFu07rQ4tbCzzoHxm1Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lignes isol\u00e9es Sous Vide: LSV","description":"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/","og_locale":"fr_FR","og_type":"article","og_title":"Lignes isol\u00e9es Sous Vide: LSV","og_description":"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.","og_url":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/","og_site_name":"Demaco Cryogenics","article_publisher":"https:\/\/www.facebook.com\/demaconl","article_modified_time":"2026-08-03T13:43:39+00:00","og_image":[{"width":1152,"height":910,"url":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/Vacuum-Insulated-Piping-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@DemacoNL","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/","url":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/","name":"Lignes isol\u00e9es Sous Vide: LSV","isPartOf":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/#primaryimage"},"image":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/#primaryimage"},"thumbnailUrl":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/Vacuum-Insulated-Piping-2.png","datePublished":"2021-02-04T07:10:16+00:00","dateModified":"2026-08-03T13:43:39+00:00","description":"Les lignes de transfert isol\u00e9es sous vide constituent la base de presque toutes les infrastructures cryog\u00e9niques. Demaco propose des lignes de transfert rigides et flexibles.","breadcrumb":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/#primaryimage","url":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/Vacuum-Insulated-Piping-2.png","contentUrl":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2021\/01\/Vacuum-Insulated-Piping-2.png","width":1152,"height":910,"caption":"Vacuum Insulated Piping"},{"@type":"BreadcrumbList","@id":"https:\/\/demaco-cryogenics.com\/fr\/produits\/lignes-isolees-sous-vide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/demaco-cryogenics.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/demaco-cryogenics.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Lignes isol\u00e9es Sous Vide: LSV"}]},{"@type":"WebSite","@id":"https:\/\/demaco-cryogenics.com\/fr\/#website","url":"https:\/\/demaco-cryogenics.com\/fr\/","name":"Demaco Cryogenics","description":"It&#039;s all about cryogenics","publisher":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demaco-cryogenics.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/demaco-cryogenics.com\/fr\/#organization","name":"Demaco Holland B.V.","url":"https:\/\/demaco-cryogenics.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/demaco-cryogenics.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2020\/11\/logoDemaco.png","contentUrl":"https:\/\/demaco-cryogenics.com\/wp-content\/uploads\/2020\/11\/logoDemaco.png","width":195,"height":32,"caption":"Demaco Holland B.V."},"image":{"@id":"https:\/\/demaco-cryogenics.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/demaconl","https:\/\/x.com\/DemacoNL","https:\/\/www.linkedin.com\/company\/demaco-holland-bv","https:\/\/www.youtube.com\/channel\/UC78jyFu07rQ4tbCzzoHxm1Q"]}]}},"_links":{"self":[{"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/products\/22087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":10,"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/products\/22087\/revisions"}],"predecessor-version":[{"id":59529,"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/products\/22087\/revisions\/59529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/media\/35122"}],"wp:attachment":[{"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/media?parent=22087"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/tags?post=22087"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/demaco-cryogenics.com\/fr\/wp-json\/wp\/v2\/industry?post=22087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}